{"id":6792,"date":"2021-04-15T18:13:22","date_gmt":"2021-04-15T22:13:22","guid":{"rendered":"https:\/\/immigrantquebec.com\/?p=6792"},"modified":"2022-03-17T10:26:49","modified_gmt":"2022-03-17T14:26:49","slug":"l-apprentissage-du-francais-pour-tous","status":"publish","type":"post","link":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/","title":{"rendered":"L\u2019apprentissage du fran\u00e7ais, pour tous"},"content":{"rendered":"<p><em>Le Qu\u00e9bec est la seule province du Canada \u00e0 ne reconna\u00eetre que le fran\u00e7ais<\/em><em>\u00a0comme langue officielle. Il est donc indispensable de comprendre et de parler le fran\u00e7ais quand on a comme projet de s&rsquo;y installer.<\/em><\/p>\n<h2><strong>La francisation, enjeu du quotidien<\/strong><\/h2>\n<p>Le fait que le Qu\u00e9bec soit une province francophone ne l\u2019emp\u00eache pas d\u2019attirer des personnes en provenance du monde entier, dont certains ma\u00eetrisent peu ou pas la langue fran\u00e7aise. Pour faciliter l\u2019accueil et la bonne int\u00e9gration de ces personnes dans la soci\u00e9t\u00e9, le minist\u00e8re de l\u2019Immigration, de la Francisation et de l\u2019Int\u00e9gration (MIFI) propose des s\u00e9ances de francisation, afin de donner aux personnes immigrantes une autonomie dans les actions quotidiennes \u00e9l\u00e9mentaires. Si le niveau atteint permet de faire des courses ou aller chez le m\u00e9decin, il risque d\u2019\u00eatre insuffisant pour le reste, fait remarquer Lee Hye Jin, originaire de Cor\u00e9e du Sud\u00a0: \u00ab\u2009J\u2019ai rencontr\u00e9 plusieurs personnes immigrantes qui trouvent que les cours de francisation offerts par le gouvernement ne suffisent pas pour acqu\u00e9rir un fran\u00e7ais comp\u00e9tent dans le milieu universitaire ou de travail\u2009\u00bb. Elle recommande ainsi de suivre un certificat universitaire en vue de monter d\u2019un cran, comme elle l\u2019a fait.<\/p>\n<h2><strong>Des premiers mots au certificat <\/strong><\/h2>\n<p>Quand Lee Hye Jin arrive au Qu\u00e9bec, elle peut compter sur des \u00e9tudes universitaires en litt\u00e9rature fran\u00e7aise, dans son pays d\u2019origine, et d\u2019un s\u00e9jour de six mois en France. De quoi lui permettre d\u2019attaquer la vie au Qu\u00e9bec sans trop de difficult\u00e9s linguistiques. Mais lorsqu\u2019elle s\u2019inscrit en composition et en r\u00e9daction fran\u00e7aises dans le but d\u2019am\u00e9liorer son niveau \u00e0 l\u2019\u00e9crit, elle r\u00e9alise que son score de test de fran\u00e7ais international (TFI) n\u2019est pas suffisant. Elle d\u00e9cide alors de suivre les cours l\u2019amenant au certificat de perfectionnement en fran\u00e7ais langue seconde de l\u2019UQAM. \u00ab\u2009J\u2019avais beau utiliser le fran\u00e7ais dans le cadre de mon travail, le fait de r\u00e9p\u00e9ter tout le temps les m\u00eames phrases me gardait bloqu\u00e9e quelque part entre du fran\u00e7ais interm\u00e9diaire et du fran\u00e7ais avanc\u00e9. Si je voulais changer d\u2019emploi ou \u00e9voluer, je devais m\u2019am\u00e9liorer\u2009\u00bb, t\u00e9moigne-t-elle.<\/p>\n<h2><strong>Du fran\u00e7ais \u00e0 tous les niveaux<\/strong><\/h2>\n<p>Juliane Bertrand, directrice du Regroupement de fran\u00e7ais langue seconde \u00e0 l\u2019UQAM d\u00e9veloppe ce qui est effectivement pr\u00e9vu pour les personnes immigrantes dont le niveau est avanc\u00e9\u00a0: \u00ab\u2009Nous proposons un certificat en une ann\u00e9e, pour arriver au niveau\u00a0C2, qui est l\u2019\u00e9quivalent d\u2019un natif hautement scolaris\u00e9\u2009\u00bb. Mais des cours propos\u00e9s par le MIFI \u00e0 l\u2019inscription \u00e0 un certificat de niveau\u00a0C1-C2, l\u2019\u00e9cart est assez significatif. Aussi fallait-il le combler avec d\u2019autres formations adapt\u00e9es pour des faux-d\u00e9butants et interm\u00e9diaires class\u00e9s\u00a0A2 ou B1, dont les connaissances sont de l\u2019ordre d\u2019une discussion courante au pr\u00e9sent. Dor\u00e9navant, c\u2019est chose faite pour cette cat\u00e9gorie de personnes, puisqu\u2019un nouveau certificat permet de sanctionner le niveau\u00a0B2. Selon ce que cherche la personne, elle peut ainsi continuer et compl\u00e9ter ses cours de fran\u00e7ais en reprenant un certificat de fran\u00e7ais langue seconde jusqu\u2019au C2, \u00e0 raison de 4 \u00e0 5\u00a0cours par session, qu\u2019il est possible de suivre \u00e0 temps complet ou \u00e0 temps partiel.<\/p>\n<h2><strong>De l\u2019anglais au chinois<\/strong><\/h2>\n<p>Dans le m\u00eame esprit, et pour r\u00e9pondre \u00e0 la demande des personnes immigrantes n\u2019ayant ni le fran\u00e7ais ni l\u2019anglais pour langue maternelle, l\u2019UQAM propose un certificat bilingue fran\u00e7ais et anglais\u00a0intitul\u00e9 <em>l\u2019Exp\u00e9rience montr\u00e9alaise<\/em>. Ce dernier permet de d\u00e9velopper ses comp\u00e9tences simultan\u00e9ment dans les deux langues. Juliane Bertrand \u00e9voque ces cours exp\u00e9rientiels de neuf heures par semaine\u00a0: \u00ab\u2009Nous y incluons trois heures de classe et six heures pour la pr\u00e9paration des travaux, mais \u00e9galement des visites culturelles et du b\u00e9n\u00e9volat dans un organisme\u00a0pour une int\u00e9gration compl\u00e8te\u2009\u00bb. L\u2019inscription d\u00e9bute au niveau B1, et il est possible d\u2019aller jusqu\u2019au C2. C\u2019est en fonction de son niveau en fran\u00e7ais et en anglais que ce dernier choisira le nombre de cours dans chaque langue.<\/p>\n<p>Enfin, pour ceux qui veulent enrichir leur fran\u00e7ais en m\u00eame temps qu\u2019une autre langue, il existe un programme de majeure en deux ans (\u00e0 temps complet) qui explore les langues et la culture. L\u2019\u00e9tudiant choisit alors le fran\u00e7ais langue seconde, ainsi qu\u2019une autre langue, qui peut \u00eatre l\u2019espagnol, l\u2019italien, le chinois, le japonais, l\u2019allemand, l\u2019arabe ou l\u2019anglais. Pour finir, il est \u00e9galement possible d\u2019obtenir un baccalaur\u00e9at par cumul de trois certificats, ou encore d\u2019un certificat et une majeure.<\/p>\n<p><em>L\u2019<\/em><a href=\"https:\/\/tv.uqam.ca\/etudier-francais-langlais-luqam-pour-souvrir-portes\" target=\"_blank\" rel=\"noopener\"><em>UQAM<\/em><\/a><em> propose plusieurs certificats et une majeure pour apprendre le fran\u00e7ais, mais \u00e9galement l\u2019anglais ainsi que d\u2019autres langues en fonction de vos desiderata et de vos besoins.\u00a0 \u00a0\u00a0Vous pouvez vous inscrire pour un certificat en une ann\u00e9e ou une majeur en 2\u00a0ans.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Qu\u00e9bec est la seule province du Canada \u00e0 ne reconna\u00eetre que le fran\u00e7ais\u00a0comme langue officielle. Il est donc indispensable de comprendre et de parler le fran\u00e7ais quand on a comme projet de s&rsquo;y installer. La francisation, enjeu du quotidien Le fait que le Qu\u00e9bec soit une province francophone ne l\u2019emp\u00eache pas d\u2019attirer des personnes [&hellip;]<\/p>\n","protected":false},"author":3491,"featured_media":6793,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[103],"tags":[],"class_list":["post-6792","post","type-post","status-publish","format-standard","has-post-thumbnail","category-conseils-d-experts","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019apprentissage du fran\u00e7ais, pour tous - Immigrant Qu\u00e9bec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019apprentissage du fran\u00e7ais, pour tous - Immigrant Qu\u00e9bec\" \/>\n<meta property=\"og:description\" content=\"Le Qu\u00e9bec est la seule province du Canada \u00e0 ne reconna\u00eetre que le fran\u00e7ais\u00a0comme langue officielle. Il est donc indispensable de comprendre et de parler le fran\u00e7ais quand on a comme projet de s&rsquo;y installer. La francisation, enjeu du quotidien Le fait que le Qu\u00e9bec soit une province francophone ne l\u2019emp\u00eache pas d\u2019attirer des personnes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/\" \/>\n<meta property=\"og:site_name\" content=\"Immigrant Qu\u00e9bec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/immigrantquebec\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-15T22:13:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-17T14:26:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/immigrantquebec.com\/fr\/wp-content\/uploads\/2022\/01\/89f366cd-7f4b-48d4-a380-979524297ac5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/\"},\"author\":{\"name\":\"Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al\",\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/#\\\/schema\\\/person\\\/dd0e58ee9bea0175550057f6affde89a\"},\"headline\":\"L\u2019apprentissage du fran\u00e7ais, pour tous\",\"datePublished\":\"2021-04-15T22:13:22+00:00\",\"dateModified\":\"2022-03-17T14:26:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/\"},\"wordCount\":873,\"publisher\":{\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/89f366cd-7f4b-48d4-a380-979524297ac5.jpg\",\"articleSection\":[\"Conseils d'experts\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/\",\"url\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/\",\"name\":\"L\u2019apprentissage du fran\u00e7ais, pour tous - Immigrant Qu\u00e9bec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/89f366cd-7f4b-48d4-a380-979524297ac5.jpg\",\"datePublished\":\"2021-04-15T22:13:22+00:00\",\"dateModified\":\"2022-03-17T14:26:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/#primaryimage\",\"url\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/89f366cd-7f4b-48d4-a380-979524297ac5.jpg\",\"contentUrl\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/89f366cd-7f4b-48d4-a380-979524297ac5.jpg\",\"width\":950,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/l-apprentissage-du-francais-pour-tous\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils d'experts\",\"item\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/conseils-d-experts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u2019apprentissage du fran\u00e7ais, pour tous\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/\",\"name\":\"Immigrant Qu\u00e9bec\",\"description\":\"Immigrer, vivre, travailler et \u00e9tudier au Qu\u00e9bec, Canada\",\"publisher\":{\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/#organization\",\"name\":\"Immigrant Qu\u00e9bec\",\"url\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-LogoIQ-20ans-RVB.png\",\"contentUrl\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/cropped-LogoIQ-20ans-RVB.png\",\"width\":1379,\"height\":442,\"caption\":\"Immigrant Qu\u00e9bec\"},\"image\":{\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/immigrantquebec\",\"https:\\\/\\\/x.com\\\/ImmigrantQuebec\",\"https:\\\/\\\/www.instagram.com\\\/immigrantquebec\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ImmigrantQc\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/#\\\/schema\\\/person\\\/dd0e58ee9bea0175550057f6affde89a\",\"name\":\"Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/0a466ed7-69ad-4a83-93f2-1008ad04c818-1-96x96.jpeg\",\"url\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/0a466ed7-69ad-4a83-93f2-1008ad04c818-1-96x96.jpeg\",\"contentUrl\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/0a466ed7-69ad-4a83-93f2-1008ad04c818-1-96x96.jpeg\",\"caption\":\"Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al\"},\"description\":\"L\u2019Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al (UQAM) est une universit\u00e9 publique francophone r\u00e9put\u00e9e pour son ouverture, son dynamisme, la qualit\u00e9 des enseignements offerts et la pertinence de ses programmes d\u2019\u00e9tudes.\",\"sameAs\":[\"https:\\\/\\\/etudier.uqam.ca\\\/\"],\"url\":\"https:\\\/\\\/immigrantquebec.com\\\/fr\\\/author\\\/universite-du-quebec-a-montreal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019apprentissage du fran\u00e7ais, pour tous - Immigrant Qu\u00e9bec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019apprentissage du fran\u00e7ais, pour tous - Immigrant Qu\u00e9bec","og_description":"Le Qu\u00e9bec est la seule province du Canada \u00e0 ne reconna\u00eetre que le fran\u00e7ais\u00a0comme langue officielle. Il est donc indispensable de comprendre et de parler le fran\u00e7ais quand on a comme projet de s&rsquo;y installer. La francisation, enjeu du quotidien Le fait que le Qu\u00e9bec soit une province francophone ne l\u2019emp\u00eache pas d\u2019attirer des personnes [&hellip;]","og_url":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/","og_site_name":"Immigrant Qu\u00e9bec","article_publisher":"https:\/\/www.facebook.com\/immigrantquebec","article_published_time":"2021-04-15T22:13:22+00:00","article_modified_time":"2022-03-17T14:26:49+00:00","og_image":[{"width":950,"height":400,"url":"https:\/\/immigrantquebec.com\/fr\/wp-content\/uploads\/2022\/01\/89f366cd-7f4b-48d4-a380-979524297ac5.jpg","type":"image\/jpeg"}],"author":"Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al","twitter_misc":{"\u00c9crit par":"Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/#article","isPartOf":{"@id":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/"},"author":{"name":"Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al","@id":"https:\/\/immigrantquebec.com\/fr\/#\/schema\/person\/dd0e58ee9bea0175550057f6affde89a"},"headline":"L\u2019apprentissage du fran\u00e7ais, pour tous","datePublished":"2021-04-15T22:13:22+00:00","dateModified":"2022-03-17T14:26:49+00:00","mainEntityOfPage":{"@id":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/"},"wordCount":873,"publisher":{"@id":"https:\/\/immigrantquebec.com\/fr\/#organization"},"image":{"@id":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/#primaryimage"},"thumbnailUrl":"https:\/\/immigrantquebec.com\/fr\/wp-content\/uploads\/2022\/01\/89f366cd-7f4b-48d4-a380-979524297ac5.jpg","articleSection":["Conseils d'experts"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/","url":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/","name":"L\u2019apprentissage du fran\u00e7ais, pour tous - Immigrant Qu\u00e9bec","isPartOf":{"@id":"https:\/\/immigrantquebec.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/#primaryimage"},"image":{"@id":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/#primaryimage"},"thumbnailUrl":"https:\/\/immigrantquebec.com\/fr\/wp-content\/uploads\/2022\/01\/89f366cd-7f4b-48d4-a380-979524297ac5.jpg","datePublished":"2021-04-15T22:13:22+00:00","dateModified":"2022-03-17T14:26:49+00:00","breadcrumb":{"@id":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/#primaryimage","url":"https:\/\/immigrantquebec.com\/fr\/wp-content\/uploads\/2022\/01\/89f366cd-7f4b-48d4-a380-979524297ac5.jpg","contentUrl":"https:\/\/immigrantquebec.com\/fr\/wp-content\/uploads\/2022\/01\/89f366cd-7f4b-48d4-a380-979524297ac5.jpg","width":950,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/l-apprentissage-du-francais-pour-tous\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/immigrantquebec.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Conseils d'experts","item":"https:\/\/immigrantquebec.com\/fr\/conseils-d-experts\/"},{"@type":"ListItem","position":3,"name":"L\u2019apprentissage du fran\u00e7ais, pour tous"}]},{"@type":"WebSite","@id":"https:\/\/immigrantquebec.com\/fr\/#website","url":"https:\/\/immigrantquebec.com\/fr\/","name":"Immigrant Qu\u00e9bec","description":"Immigrer, vivre, travailler et \u00e9tudier au Qu\u00e9bec, Canada","publisher":{"@id":"https:\/\/immigrantquebec.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/immigrantquebec.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/immigrantquebec.com\/fr\/#organization","name":"Immigrant Qu\u00e9bec","url":"https:\/\/immigrantquebec.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/immigrantquebec.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/immigrantquebec.com\/fr\/wp-content\/uploads\/2026\/07\/cropped-LogoIQ-20ans-RVB.png","contentUrl":"https:\/\/immigrantquebec.com\/fr\/wp-content\/uploads\/2026\/07\/cropped-LogoIQ-20ans-RVB.png","width":1379,"height":442,"caption":"Immigrant Qu\u00e9bec"},"image":{"@id":"https:\/\/immigrantquebec.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/immigrantquebec","https:\/\/x.com\/ImmigrantQuebec","https:\/\/www.instagram.com\/immigrantquebec","https:\/\/www.youtube.com\/user\/ImmigrantQc"]},{"@type":"Person","@id":"https:\/\/immigrantquebec.com\/fr\/#\/schema\/person\/dd0e58ee9bea0175550057f6affde89a","name":"Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/immigrantquebec.com\/fr\/wp-content\/uploads\/2022\/03\/0a466ed7-69ad-4a83-93f2-1008ad04c818-1-96x96.jpeg","url":"https:\/\/immigrantquebec.com\/fr\/wp-content\/uploads\/2022\/03\/0a466ed7-69ad-4a83-93f2-1008ad04c818-1-96x96.jpeg","contentUrl":"https:\/\/immigrantquebec.com\/fr\/wp-content\/uploads\/2022\/03\/0a466ed7-69ad-4a83-93f2-1008ad04c818-1-96x96.jpeg","caption":"Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al"},"description":"L\u2019Universit\u00e9 du Qu\u00e9bec \u00e0 Montr\u00e9al (UQAM) est une universit\u00e9 publique francophone r\u00e9put\u00e9e pour son ouverture, son dynamisme, la qualit\u00e9 des enseignements offerts et la pertinence de ses programmes d\u2019\u00e9tudes.","sameAs":["https:\/\/etudier.uqam.ca\/"],"url":"https:\/\/immigrantquebec.com\/fr\/author\/universite-du-quebec-a-montreal\/"}]}},"_links":{"self":[{"href":"https:\/\/immigrantquebec.com\/fr\/wp-json\/wp\/v2\/posts\/6792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/immigrantquebec.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/immigrantquebec.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/immigrantquebec.com\/fr\/wp-json\/wp\/v2\/users\/3491"}],"replies":[{"embeddable":true,"href":"https:\/\/immigrantquebec.com\/fr\/wp-json\/wp\/v2\/comments?post=6792"}],"version-history":[{"count":0,"href":"https:\/\/immigrantquebec.com\/fr\/wp-json\/wp\/v2\/posts\/6792\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/immigrantquebec.com\/fr\/wp-json\/wp\/v2\/media\/6793"}],"wp:attachment":[{"href":"https:\/\/immigrantquebec.com\/fr\/wp-json\/wp\/v2\/media?parent=6792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/immigrantquebec.com\/fr\/wp-json\/wp\/v2\/categories?post=6792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/immigrantquebec.com\/fr\/wp-json\/wp\/v2\/tags?post=6792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}